{"id":2213,"date":"2020-06-18T13:12:08","date_gmt":"2020-06-18T11:12:08","guid":{"rendered":"https:\/\/trustvalley.tech\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/"},"modified":"2020-06-23T11:22:26","modified_gmt":"2020-06-23T09:22:26","slug":"communique-de-presse-lancement-de-la-trust-valley","status":"publish","type":"post","link":"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/","title":{"rendered":"The Swiss Cyber Security Days will be back in Fribourg"},"content":{"rendered":"<p><span class=\"s5\">The 2nd edition of the Swiss Cyber Security Days<\/span> <span class=\"s5\">representing\u00a0<\/span><span class=\"s5\">Switzerland\u2018<\/span><span class=\"s5\">s leading<\/span> <span class=\"s5\">expertise in cyber<\/span><span class=\"s5\">security will be held at Forum Fribourg.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>The 2nd edition of the Swiss Cyber Security Days representing\u00a0Switzerland\u2018s leading expertise in cybersecurity will be held at Forum Fribourg.<\/p>\n","protected":false},"author":7,"featured_media":1743,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-2213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Swiss Cyber Security Days will be back in Fribourg - Trust Valley<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Swiss Cyber Security Days will be back in Fribourg - Trust Valley\" \/>\n<meta property=\"og:description\" content=\"The 2nd edition of the Swiss Cyber Security Days representing\u00a0Switzerland\u2018s leading expertise in cybersecurity will be held at Forum Fribourg.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/\" \/>\n<meta property=\"og:site_name\" content=\"Trust Valley\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-18T11:12:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-23T09:22:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2020\/06\/about_bg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1356\" \/>\n\t<meta property=\"og:image:height\" content=\"816\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Invit\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Invit\u00e9\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/2020\\\/06\\\/18\\\/communique-de-presse-lancement-de-la-trust-valley\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/2020\\\/06\\\/18\\\/communique-de-presse-lancement-de-la-trust-valley\\\/\"},\"author\":{\"name\":\"Invit\u00e9\",\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/#\\\/schema\\\/person\\\/8d54ac40cfbf273e74fa58f2193383e3\"},\"headline\":\"The Swiss Cyber Security Days will be back in Fribourg\",\"datePublished\":\"2020-06-18T11:12:08+00:00\",\"dateModified\":\"2020-06-23T09:22:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/2020\\\/06\\\/18\\\/communique-de-presse-lancement-de-la-trust-valley\\\/\"},\"wordCount\":33,\"image\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/2020\\\/06\\\/18\\\/communique-de-presse-lancement-de-la-trust-valley\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/trustvalley.swiss\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/about_bg.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/2020\\\/06\\\/18\\\/communique-de-presse-lancement-de-la-trust-valley\\\/\",\"url\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/2020\\\/06\\\/18\\\/communique-de-presse-lancement-de-la-trust-valley\\\/\",\"name\":\"The Swiss Cyber Security Days will be back in Fribourg - Trust Valley\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/2020\\\/06\\\/18\\\/communique-de-presse-lancement-de-la-trust-valley\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/2020\\\/06\\\/18\\\/communique-de-presse-lancement-de-la-trust-valley\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/trustvalley.swiss\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/about_bg.jpg\",\"datePublished\":\"2020-06-18T11:12:08+00:00\",\"dateModified\":\"2020-06-23T09:22:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/#\\\/schema\\\/person\\\/8d54ac40cfbf273e74fa58f2193383e3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/2020\\\/06\\\/18\\\/communique-de-presse-lancement-de-la-trust-valley\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/2020\\\/06\\\/18\\\/communique-de-presse-lancement-de-la-trust-valley\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/2020\\\/06\\\/18\\\/communique-de-presse-lancement-de-la-trust-valley\\\/#primaryimage\",\"url\":\"https:\\\/\\\/trustvalley.swiss\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/about_bg.jpg\",\"contentUrl\":\"https:\\\/\\\/trustvalley.swiss\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/about_bg.jpg\",\"width\":1356,\"height\":816,\"caption\":\"background blue\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/2020\\\/06\\\/18\\\/communique-de-presse-lancement-de-la-trust-valley\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Swiss Cyber Security Days will be back in Fribourg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/\",\"name\":\"Trust Valley\",\"description\":\"Trust Valley\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/#\\\/schema\\\/person\\\/8d54ac40cfbf273e74fa58f2193383e3\",\"name\":\"Invit\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/89e0675cc64b126e07ffd3c43b76e417a64d8c8e053a3e58122e5aeefd7153cf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/89e0675cc64b126e07ffd3c43b76e417a64d8c8e053a3e58122e5aeefd7153cf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/89e0675cc64b126e07ffd3c43b76e417a64d8c8e053a3e58122e5aeefd7153cf?s=96&d=mm&r=g\",\"caption\":\"Invit\u00e9\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Swiss Cyber Security Days will be back in Fribourg - Trust Valley","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/","og_locale":"en_US","og_type":"article","og_title":"The Swiss Cyber Security Days will be back in Fribourg - Trust Valley","og_description":"The 2nd edition of the Swiss Cyber Security Days representing\u00a0Switzerland\u2018s leading expertise in cybersecurity will be held at Forum Fribourg.","og_url":"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/","og_site_name":"Trust Valley","article_published_time":"2020-06-18T11:12:08+00:00","article_modified_time":"2020-06-23T09:22:26+00:00","og_image":[{"width":1356,"height":816,"url":"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2020\/06\/about_bg.jpg","type":"image\/jpeg"}],"author":"Invit\u00e9","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Invit\u00e9"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/#article","isPartOf":{"@id":"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/"},"author":{"name":"Invit\u00e9","@id":"https:\/\/trustvalley.swiss\/en\/#\/schema\/person\/8d54ac40cfbf273e74fa58f2193383e3"},"headline":"The Swiss Cyber Security Days will be back in Fribourg","datePublished":"2020-06-18T11:12:08+00:00","dateModified":"2020-06-23T09:22:26+00:00","mainEntityOfPage":{"@id":"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/"},"wordCount":33,"image":{"@id":"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/#primaryimage"},"thumbnailUrl":"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2020\/06\/about_bg.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/","url":"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/","name":"The Swiss Cyber Security Days will be back in Fribourg - Trust Valley","isPartOf":{"@id":"https:\/\/trustvalley.swiss\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/#primaryimage"},"image":{"@id":"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/#primaryimage"},"thumbnailUrl":"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2020\/06\/about_bg.jpg","datePublished":"2020-06-18T11:12:08+00:00","dateModified":"2020-06-23T09:22:26+00:00","author":{"@id":"https:\/\/trustvalley.swiss\/en\/#\/schema\/person\/8d54ac40cfbf273e74fa58f2193383e3"},"breadcrumb":{"@id":"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/#primaryimage","url":"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2020\/06\/about_bg.jpg","contentUrl":"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2020\/06\/about_bg.jpg","width":1356,"height":816,"caption":"background blue"},{"@type":"BreadcrumbList","@id":"https:\/\/trustvalley.swiss\/en\/2020\/06\/18\/communique-de-presse-lancement-de-la-trust-valley\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/trustvalley.swiss\/en\/"},{"@type":"ListItem","position":2,"name":"The Swiss Cyber Security Days will be back in Fribourg"}]},{"@type":"WebSite","@id":"https:\/\/trustvalley.swiss\/en\/#website","url":"https:\/\/trustvalley.swiss\/en\/","name":"Trust Valley","description":"Trust Valley","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trustvalley.swiss\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/trustvalley.swiss\/en\/#\/schema\/person\/8d54ac40cfbf273e74fa58f2193383e3","name":"Invit\u00e9","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/89e0675cc64b126e07ffd3c43b76e417a64d8c8e053a3e58122e5aeefd7153cf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/89e0675cc64b126e07ffd3c43b76e417a64d8c8e053a3e58122e5aeefd7153cf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/89e0675cc64b126e07ffd3c43b76e417a64d8c8e053a3e58122e5aeefd7153cf?s=96&d=mm&r=g","caption":"Invit\u00e9"}}]}},"_links":{"self":[{"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/posts\/2213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/comments?post=2213"}],"version-history":[{"count":0,"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/posts\/2213\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/media\/1743"}],"wp:attachment":[{"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/media?parent=2213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/categories?post=2213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/tags?post=2213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}