{"id":9282,"date":"2023-05-26T09:00:15","date_gmt":"2023-05-26T07:00:15","guid":{"rendered":"https:\/\/trustvalley.swiss\/events\/tech4trust-legal-workshop\/"},"modified":"2023-05-30T15:57:23","modified_gmt":"2023-05-30T13:57:23","slug":"tech4trust-legal-workshop","status":"publish","type":"events","link":"https:\/\/trustvalley.swiss\/en\/events\/tech4trust-legal-workshop\/","title":{"rendered":"Tech4Trust Legal Workshop"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8221;1\/1&#8243;][vc_single_image media=&#8221;9279&#8243; media_width_percent=&#8221;100&#8243; alignment=&#8221;center&#8221; border=&#8221;yes&#8221; uncode_shortcode_id=&#8221;149096&#8243;][vc_custom_heading heading_semantic=&#8221;h1&#8243; uncode_shortcode_id=&#8221;967055&#8243;]<strong>Legal Challenges and Opportunities: Practical Guidance for Founders &#8211; Legal Workshop<\/strong>[\/vc_custom_heading][\/vc_column][\/vc_row][vc_row row_height_percent=&#8221;0&#8243; back_color=&#8221;color-lxmt&#8221; overlay_alpha=&#8221;50&#8243; gutter_size=&#8221;3&#8243; column_width_percent=&#8221;100&#8243; shift_y=&#8221;0&#8243; z_index=&#8221;0&#8243; uncode_shortcode_id=&#8221;188176&#8243; back_color_type=&#8221;uncode-palette&#8221;][vc_column width=&#8221;1\/1&#8243;][vc_row_inner limit_content=&#8221;&#8221;][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text uncode_shortcode_id=&#8221;204486&#8243;]<\/p>\n<h3>Date<\/h3>\n<p>1 juin 2023<br \/>\n09h00 &#8211; 12h00[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text uncode_shortcode_id=&#8221;151870&#8243;]<\/p>\n<h3>Location<\/h3>\n<p>Trust Village<br \/>\nUnlimitrust<br \/>\nRte des Flumeaux 42[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243;][vc_column_text uncode_shortcode_id=&#8221;273784&#8243;]<\/p>\n<h3>Registration<\/h3>\n<p>[\/vc_column_text][vc_button button_color=&#8221;color-vyce&#8221; border_width=&#8221;0&#8243; uncode_shortcode_id=&#8221;116536&#8243; link=&#8221;url:https%3A%2F%2Fapp.decilio.ch%2Fforms%2F89a42067-b13c-40a4-8714-4db60de6b19c|title:Registration|target:_blank|&#8221; button_color_type=&#8221;uncode-palette&#8221;]Registration[\/vc_button][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;2\/3&#8243;][vc_custom_heading uncode_shortcode_id=&#8221;102496&#8243;]About the event[\/vc_custom_heading][vc_row_inner limit_content=&#8221;&#8221;][vc_column_inner width=&#8221;1\/1&#8243;][vc_column_text text_lead=&#8221;yes&#8221; uncode_shortcode_id=&#8221;674564&#8243;]Join us for a practical workshop focused on legal challenges and opportunities for founders. Gain valuable insights from industry experts who will share effective strategies and best practices to help you navigate your startup&#8217;s legal journey.<\/p>\n<p>Livestream Zoom: <a href=\"https:\/\/us02web.zoom.us\/j\/84546103007\">https:\/\/us02web.zoom.us\/j\/84546103007<\/a><\/p>\n<p>Our exceptional lineup of speakers will share their expertise and knowledge across various domains:<\/p>\n<ul>\n<li>Alain Alberini, Avocat au barreau\/Attorney-at-Law, sigma legal<\/li>\n<li>Vikram Chand, Associate Professor of Law at the University of Lausanne &#8211; UNIL<\/li>\n<li>Laurence Devun-Turner, Attorney at Kellerhals Carrard<\/li>\n<li>Alexandre Gachet, Attorney at Kellerhals Carrand<\/li>\n<li>Sol\u00e8ne Tierny Oesch, Partner, Legal Advisory, Services &amp; Education everwise LLC<\/li>\n<li>Basile Walder, Attorney-at-law, Senior Associate at Etude VISCHER<\/li>\n<\/ul>\n<p>Tech4Trust Alumni, Aur\u00e9lien Tisserand from Rumya and Nagib Aouini from DuoKey, will also share their valuable insights gained from their own legal journeys.[\/vc_column_text][vc_custom_heading uncode_shortcode_id=&#8221;144993&#8243;]Registration[\/vc_custom_heading][vc_button button_color=&#8221;color-vyce&#8221; border_width=&#8221;0&#8243; uncode_shortcode_id=&#8221;105298&#8243; link=&#8221;url:https%3A%2F%2Fapp.decilio.ch%2Fforms%2F89a42067-b13c-40a4-8714-4db60de6b19c|title:Registration|target:_blank|&#8221; button_color_type=&#8221;uncode-palette&#8221;]Registration[\/vc_button][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/3&#8243; uncode_shortcode_id=&#8221;145829&#8243;][vc_custom_heading uncode_shortcode_id=&#8221;170984&#8243;]Key focus areas[\/vc_custom_heading][vc_column_text uncode_shortcode_id=&#8221;148188&#8243;]<\/p>\n<ul>\n<li>Entity Formation<\/li>\n<li>Intellectual Property (IP) Protection<\/li>\n<li>Contracts, agreements and employment law<\/li>\n<li>Securities and Fundraising<\/li>\n<li>Privacy and Data Protection and\u00a0Regulatory Compliance<\/li>\n<li>Tax Obligations<\/li>\n<li>Corporate gouvernance<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Join us on June 1 for a practical workshop focused on legal challenges and opportunities for founders.<\/p>\n","protected":false},"featured_media":9280,"template":"","projet":[],"class_list":["post-9282","events","type-events","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tech4Trust Legal Workshop - Trust Valley<\/title>\n<meta name=\"description\" content=\"Join us on June 1 at the Trust Village for a practical workshop focused on legal challenges and opportunities for founders.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trustvalley.swiss\/en\/events\/tech4trust-legal-workshop\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tech4Trust Legal Workshop - Trust Valley\" \/>\n<meta property=\"og:description\" content=\"Join us on June 1 at the Trust Village for a practical workshop focused on legal challenges and opportunities for founders.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trustvalley.swiss\/en\/events\/tech4trust-legal-workshop\/\" \/>\n<meta property=\"og:site_name\" content=\"Trust Valley\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-30T13:57:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2023\/05\/tech4trust-legal-workshop-2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/tech4trust-legal-workshop\\\/\",\"url\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/tech4trust-legal-workshop\\\/\",\"name\":\"Tech4Trust Legal Workshop - Trust Valley\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/tech4trust-legal-workshop\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/tech4trust-legal-workshop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/trustvalley.swiss\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/tech4trust-legal-workshop-2023.jpg\",\"datePublished\":\"2023-05-26T07:00:15+00:00\",\"dateModified\":\"2023-05-30T13:57:23+00:00\",\"description\":\"Join us on June 1 at the Trust Village for a practical workshop focused on legal challenges and opportunities for founders.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/tech4trust-legal-workshop\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/tech4trust-legal-workshop\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/tech4trust-legal-workshop\\\/#primaryimage\",\"url\":\"https:\\\/\\\/trustvalley.swiss\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/tech4trust-legal-workshop-2023.jpg\",\"contentUrl\":\"https:\\\/\\\/trustvalley.swiss\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/tech4trust-legal-workshop-2023.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/tech4trust-legal-workshop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tech4Trust Legal Workshop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/\",\"name\":\"Trust Valley\",\"description\":\"Trust Valley\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tech4Trust Legal Workshop - Trust Valley","description":"Join us on June 1 at the Trust Village for a practical workshop focused on legal challenges and opportunities for founders.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trustvalley.swiss\/en\/events\/tech4trust-legal-workshop\/","og_locale":"en_US","og_type":"article","og_title":"Tech4Trust Legal Workshop - Trust Valley","og_description":"Join us on June 1 at the Trust Village for a practical workshop focused on legal challenges and opportunities for founders.","og_url":"https:\/\/trustvalley.swiss\/en\/events\/tech4trust-legal-workshop\/","og_site_name":"Trust Valley","article_modified_time":"2023-05-30T13:57:23+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2023\/05\/tech4trust-legal-workshop-2023.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/trustvalley.swiss\/en\/events\/tech4trust-legal-workshop\/","url":"https:\/\/trustvalley.swiss\/en\/events\/tech4trust-legal-workshop\/","name":"Tech4Trust Legal Workshop - Trust Valley","isPartOf":{"@id":"https:\/\/trustvalley.swiss\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trustvalley.swiss\/en\/events\/tech4trust-legal-workshop\/#primaryimage"},"image":{"@id":"https:\/\/trustvalley.swiss\/en\/events\/tech4trust-legal-workshop\/#primaryimage"},"thumbnailUrl":"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2023\/05\/tech4trust-legal-workshop-2023.jpg","datePublished":"2023-05-26T07:00:15+00:00","dateModified":"2023-05-30T13:57:23+00:00","description":"Join us on June 1 at the Trust Village for a practical workshop focused on legal challenges and opportunities for founders.","breadcrumb":{"@id":"https:\/\/trustvalley.swiss\/en\/events\/tech4trust-legal-workshop\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trustvalley.swiss\/en\/events\/tech4trust-legal-workshop\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/trustvalley.swiss\/en\/events\/tech4trust-legal-workshop\/#primaryimage","url":"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2023\/05\/tech4trust-legal-workshop-2023.jpg","contentUrl":"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2023\/05\/tech4trust-legal-workshop-2023.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/trustvalley.swiss\/en\/events\/tech4trust-legal-workshop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/trustvalley.swiss\/en\/"},{"@type":"ListItem","position":2,"name":"Tech4Trust Legal Workshop"}]},{"@type":"WebSite","@id":"https:\/\/trustvalley.swiss\/en\/#website","url":"https:\/\/trustvalley.swiss\/en\/","name":"Trust Valley","description":"Trust Valley","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trustvalley.swiss\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/events\/9282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/types\/events"}],"version-history":[{"count":3,"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/events\/9282\/revisions"}],"predecessor-version":[{"id":9303,"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/events\/9282\/revisions\/9303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/media\/9280"}],"wp:attachment":[{"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/media?parent=9282"}],"wp:term":[{"taxonomy":"projet","embeddable":true,"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/projet?post=9282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}