{"id":4881,"date":"2021-09-10T22:42:48","date_gmt":"2021-09-10T20:42:48","guid":{"rendered":"https:\/\/trustvalley.swiss\/events\/trust-valley-day\/"},"modified":"2021-09-10T22:44:18","modified_gmt":"2021-09-10T20:44:18","slug":"trust-valley-day","status":"publish","type":"events","link":"https:\/\/trustvalley.swiss\/en\/events\/trust-valley-day\/","title":{"rendered":"Trust Valley Day"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243; link_to=&#8221;url:https%3A%2F%2Ftrustvalley.swiss%2Ftrust-valley-day-2021%2F&#8221;][vc_column_text]The Trust Valley is pleased to invite you\u00a0<b>ONLINE\u00a0on\u00a0October 4th<\/b>\u00a0for the annual event of the Trust Valley.<\/p>\n<p><b><span lang=\"EN-US\">Digital Trust and Cybersecurity focused on Talents<\/span><\/b>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/1&#8243;][vc_button button_color=&#8221;accent&#8221; size=&#8221;btn-lg&#8221; border_width=&#8221;0&#8243; link=&#8221;url:https%3A%2F%2Ftrustvalley.swiss%2Fen%2Ftrust-valley-day-2021%2F|title:Trust%20Valley%20Day|&#8221;]View the event[\/vc_button][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243; link_to=&#8221;url:https%3A%2F%2Ftrustvalley.swiss%2Ftrust-valley-day-2021%2F&#8221;][vc_column_text]The Trust Valley is pleased to invite you\u00a0ONLINE\u00a0on\u00a0October 4th\u00a0for [&hellip;]<\/p>\n","protected":false},"featured_media":1134,"template":"","projet":[],"class_list":["post-4881","events","type-events","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trust Valley Day - Trust Valley<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trustvalley.swiss\/en\/events\/trust-valley-day\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trust Valley Day - Trust Valley\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243; link_to=&#8221;url:https%3A%2F%2Ftrustvalley.swiss%2Ftrust-valley-day-2021%2F&#8221;][vc_column_text]The Trust Valley is pleased to invite you\u00a0ONLINE\u00a0on\u00a0October 4th\u00a0for [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trustvalley.swiss\/en\/events\/trust-valley-day\/\" \/>\n<meta property=\"og:site_name\" content=\"Trust Valley\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-10T20:44:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2020\/06\/cropped-faviconx2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/trust-valley-day\\\/\",\"url\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/trust-valley-day\\\/\",\"name\":\"Trust Valley Day - Trust Valley\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/trust-valley-day\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/trust-valley-day\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/trustvalley.swiss\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-faviconx2.png\",\"datePublished\":\"2021-09-10T20:42:48+00:00\",\"dateModified\":\"2021-09-10T20:44:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/trust-valley-day\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/trust-valley-day\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/trust-valley-day\\\/#primaryimage\",\"url\":\"https:\\\/\\\/trustvalley.swiss\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-faviconx2.png\",\"contentUrl\":\"https:\\\/\\\/trustvalley.swiss\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-faviconx2.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/events\\\/trust-valley-day\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trust Valley Day\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/\",\"name\":\"Trust Valley\",\"description\":\"Trust Valley\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/trustvalley.swiss\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trust Valley Day - Trust Valley","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trustvalley.swiss\/en\/events\/trust-valley-day\/","og_locale":"en_US","og_type":"article","og_title":"Trust Valley Day - Trust Valley","og_description":"[vc_row][vc_column column_width_percent=&#8221;100&#8243; gutter_size=&#8221;3&#8243; overlay_alpha=&#8221;50&#8243; shift_x=&#8221;0&#8243; shift_y=&#8221;0&#8243; shift_y_down=&#8221;0&#8243; z_index=&#8221;0&#8243; medium_width=&#8221;0&#8243; mobile_width=&#8221;0&#8243; width=&#8221;1\/1&#8243; link_to=&#8221;url:https%3A%2F%2Ftrustvalley.swiss%2Ftrust-valley-day-2021%2F&#8221;][vc_column_text]The Trust Valley is pleased to invite you\u00a0ONLINE\u00a0on\u00a0October 4th\u00a0for [&hellip;]","og_url":"https:\/\/trustvalley.swiss\/en\/events\/trust-valley-day\/","og_site_name":"Trust Valley","article_modified_time":"2021-09-10T20:44:18+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2020\/06\/cropped-faviconx2.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/trustvalley.swiss\/en\/events\/trust-valley-day\/","url":"https:\/\/trustvalley.swiss\/en\/events\/trust-valley-day\/","name":"Trust Valley Day - Trust Valley","isPartOf":{"@id":"https:\/\/trustvalley.swiss\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trustvalley.swiss\/en\/events\/trust-valley-day\/#primaryimage"},"image":{"@id":"https:\/\/trustvalley.swiss\/en\/events\/trust-valley-day\/#primaryimage"},"thumbnailUrl":"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2020\/06\/cropped-faviconx2.png","datePublished":"2021-09-10T20:42:48+00:00","dateModified":"2021-09-10T20:44:18+00:00","breadcrumb":{"@id":"https:\/\/trustvalley.swiss\/en\/events\/trust-valley-day\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trustvalley.swiss\/en\/events\/trust-valley-day\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/trustvalley.swiss\/en\/events\/trust-valley-day\/#primaryimage","url":"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2020\/06\/cropped-faviconx2.png","contentUrl":"https:\/\/trustvalley.swiss\/wp-content\/uploads\/2020\/06\/cropped-faviconx2.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/trustvalley.swiss\/en\/events\/trust-valley-day\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/trustvalley.swiss\/en\/"},{"@type":"ListItem","position":2,"name":"Trust Valley Day"}]},{"@type":"WebSite","@id":"https:\/\/trustvalley.swiss\/en\/#website","url":"https:\/\/trustvalley.swiss\/en\/","name":"Trust Valley","description":"Trust Valley","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trustvalley.swiss\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/events\/4881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/types\/events"}],"version-history":[{"count":3,"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/events\/4881\/revisions"}],"predecessor-version":[{"id":4884,"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/events\/4881\/revisions\/4884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/media\/1134"}],"wp:attachment":[{"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/media?parent=4881"}],"wp:term":[{"taxonomy":"projet","embeddable":true,"href":"https:\/\/trustvalley.swiss\/en\/wp-json\/wp\/v2\/projet?post=4881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}